{"id":1107,"count":1,"description":"","link":"https:\/\/burgonderdelen.nl\/en\/airco1640746058\/","name":"Airco","slug":"airco1640746058","taxonomy":"product_cat","parent":1101,"meta":[],"menu_order":300,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Airco Archieven - Burg Onderdelen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/burgonderdelen.nl\/en\/airco1640746058\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Airco Archieven - Burg Onderdelen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/burgonderdelen.nl\/en\/airco1640746058\/\" \/>\n<meta property=\"og:site_name\" content=\"Burg Onderdelen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/airco1640746058\\\/\",\"url\":\"https:\\\/\\\/burgonderdelen.nl\\\/airco1640746058\\\/\",\"name\":\"Airco Archieven - Burg Onderdelen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/airco1640746058\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/airco1640746058\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/burgonderdelen.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dacia\",\"item\":\"https:\\\/\\\/burgonderdelen.nl\\\/dacia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lodgy 03\\\/2012+\",\"item\":\"https:\\\/\\\/burgonderdelen.nl\\\/lodgy-032012\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Airco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/#website\",\"url\":\"https:\\\/\\\/burgonderdelen.nl\\\/\",\"name\":\"Burg Onderdelen\",\"description\":\"Uw specialist in auto onderdelen\",\"publisher\":{\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/burgonderdelen.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/#organization\",\"name\":\"Burg Onderdelen\",\"url\":\"https:\\\/\\\/burgonderdelen.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/burgonderdelen.nl\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-burgonderdelen-large.png\",\"contentUrl\":\"https:\\\/\\\/burgonderdelen.nl\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-burgonderdelen-large.png\",\"width\":483,\"height\":279,\"caption\":\"Burg Onderdelen\"},\"image\":{\"@id\":\"https:\\\/\\\/burgonderdelen.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Airco Archieven - Burg Onderdelen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/burgonderdelen.nl\/en\/airco1640746058\/","og_locale":"en_US","og_type":"article","og_title":"Airco Archieven - Burg Onderdelen","og_url":"https:\/\/burgonderdelen.nl\/en\/airco1640746058\/","og_site_name":"Burg Onderdelen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/burgonderdelen.nl\/airco1640746058\/","url":"https:\/\/burgonderdelen.nl\/airco1640746058\/","name":"Airco Archieven - Burg Onderdelen","isPartOf":{"@id":"https:\/\/burgonderdelen.nl\/#website"},"breadcrumb":{"@id":"https:\/\/burgonderdelen.nl\/airco1640746058\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/burgonderdelen.nl\/airco1640746058\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/burgonderdelen.nl\/"},{"@type":"ListItem","position":2,"name":"Dacia","item":"https:\/\/burgonderdelen.nl\/dacia\/"},{"@type":"ListItem","position":3,"name":"Lodgy 03\/2012+","item":"https:\/\/burgonderdelen.nl\/lodgy-032012\/"},{"@type":"ListItem","position":4,"name":"Airco"}]},{"@type":"WebSite","@id":"https:\/\/burgonderdelen.nl\/#website","url":"https:\/\/burgonderdelen.nl\/","name":"Burg Onderdelen","description":"Uw specialist in auto onderdelen","publisher":{"@id":"https:\/\/burgonderdelen.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/burgonderdelen.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/burgonderdelen.nl\/#organization","name":"Burg Onderdelen","url":"https:\/\/burgonderdelen.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/burgonderdelen.nl\/#\/schema\/logo\/image\/","url":"https:\/\/burgonderdelen.nl\/wp-content\/uploads\/2021\/07\/logo-burgonderdelen-large.png","contentUrl":"https:\/\/burgonderdelen.nl\/wp-content\/uploads\/2021\/07\/logo-burgonderdelen-large.png","width":483,"height":279,"caption":"Burg Onderdelen"},"image":{"@id":"https:\/\/burgonderdelen.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/burgonderdelen.nl\/en\/wp-json\/wp\/v2\/product_cat\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/burgonderdelen.nl\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/burgonderdelen.nl\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/burgonderdelen.nl\/en\/wp-json\/wp\/v2\/product_cat\/1101"}],"wp:post_type":[{"href":"https:\/\/burgonderdelen.nl\/en\/wp-json\/wp\/v2\/product?product_cat=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}